{"id":1847,"date":"2021-12-21T07:03:52","date_gmt":"2021-12-21T07:03:52","guid":{"rendered":"https:\/\/pablocarpintero.es\/?p=1847"},"modified":"2024-09-19T09:41:32","modified_gmt":"2024-09-19T09:41:32","slug":"a-ponteira-do-ti-carrico","status":"publish","type":"post","link":"https:\/\/pablocarpintero.es\/es\/a-ponteira-do-ti-carrico\/","title":{"rendered":"A ponteira do Ti Carri\u00e7o"},"content":{"rendered":"<p>Joaquim Pereira, &#8220;O Ti Carri\u00e7o&#8221; empregou unha parte significativa da s\u00faa longa vida como gaiteiro un punteiro fabricado polo artes\u00e1n coimbr\u00e1 Jos\u00e9 Mendes Seco. As\u00ed sona este <a href=\"https:\/\/pablocarpintero.es\/es\/producto\/ponteira-de-joaquim-pereira-ti-carrico\/\">punteiro<\/a> en mans do noso amigo Ant\u00f3nio Freire, que interpreta unha marcha acompa\u00f1ado por Paulo Jesus, que toca unha <a href=\"https:\/\/pablocarpintero.es\/es\/producto\/caixa-coimbra\/\">r\u00e9plica da caixa dos Melos da Barreira<\/a>, tam\u00e9n feita por n\u00f3s. O bombo corre a cargo de Roger Lee.   <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"R\u00e9plica da ponteira do Ti Carri\u00e7o. Marcha por Ant\u00f3nio Freire, Paulo Jesus e Riger Lee\" width=\"1333\" height=\"1000\" src=\"https:\/\/www.youtube.com\/embed\/4jQobInGdxQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p>Tr\u00e1tase dun punteiro que est\u00e1 moi pr\u00f3ximo ao Sib, unha t\u00f3nica moi grave trat\u00e1ndose da zona de Coimbra, onde os punteiros antigos adoitan ter t\u00f3nicas moi agudas. Ten un timbre moi nasal, doce e caracter\u00edstico. A s\u00faa escala orixinal \u00e9 un modo portugu\u00e9s, \u00e9 dicir, unha escala modal non definida na teor\u00eda medieval que ten o terceiro grao moi rebaixado, unha subt\u00f3nica algo alta, e o resto de graos moi pr\u00f3ximos \u00e1 escala temperada. Podemos obter con el un modo de Re rebaixando o s\u00e9timo grao empregando unha dixitaci\u00f3n de forquita. Con moi lixeiras modificaci\u00f3ns na colocaci\u00f3n dos furados foinos posible conseguir a partir deste punteiro unha escala temperada e crom\u00e1tica en Sib. <\/p>","protected":false},"excerpt":{"rendered":"<p>Joaquim Pereira, &#8220;O Ti Carri\u00e7o&#8221; empregou unha parte significativa da s\u00faa longa vida como gaiteiro un punteiro fabricado polo artes\u00e1n coimbr\u00e1 Jos\u00e9 Mendes Seco. As\u00ed sona este punteiro en mans do noso amigo Ant\u00f3nio Freire, que interpreta unha marcha acompa\u00f1ado por Paulo Jesus, que toca unha r\u00e9plica da caixa dos Melos da Barreira, tam\u00e9n feita [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1847","post","type-post","status-publish","format-standard","hentry","category-instrumentos-musicais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A ponteira do Ti Carri\u00e7o - Pablo Carpintero<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pablocarpintero.es\/es\/a-ponteira-do-ti-carrico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A ponteira do Ti Carri\u00e7o - Pablo Carpintero\" \/>\n<meta property=\"og:description\" content=\"Joaquim Pereira, &#8220;O Ti Carri\u00e7o&#8221; empregou unha parte significativa da s\u00faa longa vida como gaiteiro un punteiro fabricado polo artes\u00e1n coimbr\u00e1 Jos\u00e9 Mendes Seco. As\u00ed sona este punteiro en mans do noso amigo Ant\u00f3nio Freire, que interpreta unha marcha acompa\u00f1ado por Paulo Jesus, que toca unha r\u00e9plica da caixa dos Melos da Barreira, tam\u00e9n feita [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pablocarpintero.es\/es\/a-ponteira-do-ti-carrico\/\" \/>\n<meta property=\"og:site_name\" content=\"Pablo Carpintero\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-21T07:03:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-19T09:41:32+00:00\" \/>\n<meta name=\"author\" content=\"pablo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"pablo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/pablocarpintero.es\/a-ponteira-do-ti-carrico\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/pablocarpintero.es\/a-ponteira-do-ti-carrico\/\"},\"author\":{\"name\":\"pablo\",\"@id\":\"https:\/\/pablocarpintero.es\/#\/schema\/person\/a964d2df7b9dd44c619384f2569f2972\"},\"headline\":\"A ponteira do Ti Carri\u00e7o\",\"datePublished\":\"2021-12-21T07:03:52+00:00\",\"dateModified\":\"2024-09-19T09:41:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/pablocarpintero.es\/a-ponteira-do-ti-carrico\/\"},\"wordCount\":212,\"articleSection\":[\"Instrumentos musicais\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pablocarpintero.es\/a-ponteira-do-ti-carrico\/\",\"url\":\"https:\/\/pablocarpintero.es\/a-ponteira-do-ti-carrico\/\",\"name\":\"A ponteira do Ti Carri\u00e7o - Pablo Carpintero\",\"isPartOf\":{\"@id\":\"https:\/\/pablocarpintero.es\/#website\"},\"datePublished\":\"2021-12-21T07:03:52+00:00\",\"dateModified\":\"2024-09-19T09:41:32+00:00\",\"author\":{\"@id\":\"https:\/\/pablocarpintero.es\/#\/schema\/person\/a964d2df7b9dd44c619384f2569f2972\"},\"breadcrumb\":{\"@id\":\"https:\/\/pablocarpintero.es\/a-ponteira-do-ti-carrico\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pablocarpintero.es\/a-ponteira-do-ti-carrico\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pablocarpintero.es\/a-ponteira-do-ti-carrico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/pablocarpintero.es\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A ponteira do Ti Carri\u00e7o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pablocarpintero.es\/#website\",\"url\":\"https:\/\/pablocarpintero.es\/\",\"name\":\"Pablo Carpintero\",\"description\":\"Otro sitio realizado con WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pablocarpintero.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/pablocarpintero.es\/#\/schema\/person\/a964d2df7b9dd44c619384f2569f2972\",\"name\":\"pablo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/fb279e06fe3f9eacc04cd2598b4554448ca3e269fc535a61f2c7063a79133dc8?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fb279e06fe3f9eacc04cd2598b4554448ca3e269fc535a61f2c7063a79133dc8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fb279e06fe3f9eacc04cd2598b4554448ca3e269fc535a61f2c7063a79133dc8?s=96&d=mm&r=g\",\"caption\":\"pablo\"},\"sameAs\":[\"https:\/\/pablocarpintero.es\"],\"url\":\"https:\/\/pablocarpintero.es\/es\/author\/pablo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A ponteira do Ti Carri\u00e7o - Pablo Carpintero","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pablocarpintero.es\/es\/a-ponteira-do-ti-carrico\/","og_locale":"es_ES","og_type":"article","og_title":"A ponteira do Ti Carri\u00e7o - Pablo Carpintero","og_description":"Joaquim Pereira, &#8220;O Ti Carri\u00e7o&#8221; empregou unha parte significativa da s\u00faa longa vida como gaiteiro un punteiro fabricado polo artes\u00e1n coimbr\u00e1 Jos\u00e9 Mendes Seco. As\u00ed sona este punteiro en mans do noso amigo Ant\u00f3nio Freire, que interpreta unha marcha acompa\u00f1ado por Paulo Jesus, que toca unha r\u00e9plica da caixa dos Melos da Barreira, tam\u00e9n feita [&hellip;]","og_url":"https:\/\/pablocarpintero.es\/es\/a-ponteira-do-ti-carrico\/","og_site_name":"Pablo Carpintero","article_published_time":"2021-12-21T07:03:52+00:00","article_modified_time":"2024-09-19T09:41:32+00:00","author":"pablo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"pablo","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pablocarpintero.es\/a-ponteira-do-ti-carrico\/#article","isPartOf":{"@id":"https:\/\/pablocarpintero.es\/a-ponteira-do-ti-carrico\/"},"author":{"name":"pablo","@id":"https:\/\/pablocarpintero.es\/#\/schema\/person\/a964d2df7b9dd44c619384f2569f2972"},"headline":"A ponteira do Ti Carri\u00e7o","datePublished":"2021-12-21T07:03:52+00:00","dateModified":"2024-09-19T09:41:32+00:00","mainEntityOfPage":{"@id":"https:\/\/pablocarpintero.es\/a-ponteira-do-ti-carrico\/"},"wordCount":212,"articleSection":["Instrumentos musicais"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/pablocarpintero.es\/a-ponteira-do-ti-carrico\/","url":"https:\/\/pablocarpintero.es\/a-ponteira-do-ti-carrico\/","name":"A ponteira do Ti Carri\u00e7o - Pablo Carpintero","isPartOf":{"@id":"https:\/\/pablocarpintero.es\/#website"},"datePublished":"2021-12-21T07:03:52+00:00","dateModified":"2024-09-19T09:41:32+00:00","author":{"@id":"https:\/\/pablocarpintero.es\/#\/schema\/person\/a964d2df7b9dd44c619384f2569f2972"},"breadcrumb":{"@id":"https:\/\/pablocarpintero.es\/a-ponteira-do-ti-carrico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pablocarpintero.es\/a-ponteira-do-ti-carrico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/pablocarpintero.es\/a-ponteira-do-ti-carrico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pablocarpintero.es\/inicio\/"},{"@type":"ListItem","position":2,"name":"A ponteira do Ti Carri\u00e7o"}]},{"@type":"WebSite","@id":"https:\/\/pablocarpintero.es\/#website","url":"https:\/\/pablocarpintero.es\/","name":"Pablo Carpintero","description":"Otro sitio realizado con WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pablocarpintero.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/pablocarpintero.es\/#\/schema\/person\/a964d2df7b9dd44c619384f2569f2972","name":"pablo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fb279e06fe3f9eacc04cd2598b4554448ca3e269fc535a61f2c7063a79133dc8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fb279e06fe3f9eacc04cd2598b4554448ca3e269fc535a61f2c7063a79133dc8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fb279e06fe3f9eacc04cd2598b4554448ca3e269fc535a61f2c7063a79133dc8?s=96&d=mm&r=g","caption":"pablo"},"sameAs":["https:\/\/pablocarpintero.es"],"url":"https:\/\/pablocarpintero.es\/es\/author\/pablo\/"}]}},"_links":{"self":[{"href":"https:\/\/pablocarpintero.es\/es\/wp-json\/wp\/v2\/posts\/1847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pablocarpintero.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pablocarpintero.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pablocarpintero.es\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pablocarpintero.es\/es\/wp-json\/wp\/v2\/comments?post=1847"}],"version-history":[{"count":1,"href":"https:\/\/pablocarpintero.es\/es\/wp-json\/wp\/v2\/posts\/1847\/revisions"}],"predecessor-version":[{"id":1848,"href":"https:\/\/pablocarpintero.es\/es\/wp-json\/wp\/v2\/posts\/1847\/revisions\/1848"}],"wp:attachment":[{"href":"https:\/\/pablocarpintero.es\/es\/wp-json\/wp\/v2\/media?parent=1847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pablocarpintero.es\/es\/wp-json\/wp\/v2\/categories?post=1847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pablocarpintero.es\/es\/wp-json\/wp\/v2\/tags?post=1847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}