{"id":813,"date":"2021-11-08T07:37:28","date_gmt":"2021-11-08T07:37:28","guid":{"rendered":"https:\/\/pablocarpintero.es\/?post_type=product&#038;p=813"},"modified":"2025-03-29T07:35:40","modified_gmt":"2025-03-29T07:35:40","slug":"gaita-de-fol-de-julio-prada","status":"publish","type":"product","link":"https:\/\/pablocarpintero.es\/es\/producto\/gaita-de-fol-de-julio-prada\/","title":{"rendered":"Gaita de fuelle de Julio Prada"},"content":{"rendered":"<p><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span>Julio Prada (1924-2005) foi gaiteiro en Ungilde (Seabra, Zamora), un dos mitos desta terra e unha referencia para os gaiteiros do noroeste peninsular. Como t\u00f3dolos grandes gaiteiros empregou unha formidable gaita que, \u00e1 s\u00faa morte, cedeu o seu compa\u00f1eiro de alboradas Edelio Gonz\u00e1lez, gran tamboriteiro e cantador onde os haxa. Edelio depositou esta fermosa gaita, para que todos a poidamos admirar, no Museo Etnogr\u00e1fico de Zamora.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Tr\u00e1tase dunha gaita propiamente xabresa, probablemente herdada doutro gaiteiro anterior e polo tanto moi antiga, cunha t\u00f3nica preto do Do e cunha escala en modo xabr\u00e9s, \u00e9 dicir, moi semellante ao modo de La (modo menor), pero cun segundo grao bastante rebaixado. Reproducimos este fermoso instrumento e, en base a el e modificando unicamente a posici\u00f3n e di\u00e1metro dalg\u00fans furados, \u00e9 dicir, mantendo o seu timbre caracter\u00edstico, fabricamos tam\u00e9n un punteiro xabr\u00e9s crom\u00e1tico e temperado en Do [enlace a este producto].<\/p>\n<p>A gaita de Julio Prada ten un potent\u00edsimo son, tanto no ronc\u00f3n coma no punteiro; este toca empregando palletas fabricadas ao modo antigo xabr\u00e9s, ou sexa, fabricadas usando s\u00f3 a parte branda da cana. \u00c9 un punteiro cun son moi potente e lixeiro na emisi\u00f3n das notas, non entanto, esta gaita \u00e9 un instrumento que require un certo aprendizaxe para ser ben tocada, pois o ronc\u00f3n \u00e9 sensible \u00e1s variaci\u00f3ns bruscas de tempero e o punteiro require unha presi\u00f3n intermedia. <span class=\"Apple-converted-space\">\u00a0 \u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<div  class='avia-video av-earhp-0e6a56cd1de567e4e0c3bddf34261269 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/www.youtube.com\/watch?v=niyqtzDUU3o'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Corrido sanabres coa r\u00e9plica da gaita de Julio Prada\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/niyqtzDUU3o?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div>\n<p>&nbsp;<\/p>\n<div  class='avia-video av-atgot-d5c13e4364ce7e7d3228a1b3f39cdc36 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/www.youtube.com\/watch?v=AK7koTSDOE0'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Mui\u00f1eira galega coa r\u00e9plica da gaita de Julio Prada\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/AK7koTSDOE0?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><strong>Compra por encomenda<\/strong><\/p>\n<p class=\"p1\">Debido \u00e1s caracter\u00edsticas das r\u00e9plicas das gaitas de fol antigas, estas non te\u00f1en un prezo fixo asignado, que depender\u00e1 do tipo de madeira e outras caracter\u00edsticas est\u00e9ticas que podes escoller como anelados en diferentes materiais,\u00a0 freques ou reberetados dos vestidos. Todas as r\u00e9plicas de gaitas de fol te\u00f1en unha demora que depende da nosa lista de espera. Consulta con n\u00f3s para saber m\u00e1is.<\/p>\n<div  class='avia-button-wrap av-7w2e1-2cfff7366207172118f91cc6d7012c90-wrap avia-button-center  avia-builder-el-2  el_after_av_video  avia-builder-el-last '><a href='https:\/\/pablocarpintero.es\/contactar\/'  class='avia-button av-7w2e1-2cfff7366207172118f91cc6d7012c90 av-link-btn avia-icon_select-yes-left-icon avia-size-small avia-position-center avia-color-theme-color'   aria-label=\"Consulte a informaci\u00f3n de prezos\"><span class='avia_button_icon avia_button_icon_left avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue81f' data-av_iconfont='entypo-fontello' ><\/span><span class='avia_iconbox_title' >Consulte a informaci\u00f3n de prezos<\/span><\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\ufeffJulio Prada (1924-2005) foi gaiteiro en Ungilde (Seabra, Zamora), un dos mitos desta terra e unha referencia para os gaiteiros do noroeste peninsular. Como t\u00f3dolos grandes gaiteiros empregou unha formidable gaita que, \u00e1 s\u00faa morte, cedeu o seu compa\u00f1eiro de alboradas Edelio Gonz\u00e1lez, gran tamboriteiro e cantador onde os haxa. Edelio depositou esta fermosa gaita, [&hellip;]<\/p>\n","protected":false},"featured_media":2613,"comment_status":"open","ping_status":"closed","template":"","meta":{"give_campaign_id":0,"_joinchat":[]},"product_brand":[],"product_cat":[20,18,26],"product_tag":[],"class_list":["post-813","product","type-product","status-publish","has-post-thumbnail","product_cat-gaitas-de-fol","product_cat-instrumentos-musicales","product_cat-replicas-de-gaitas-xabresas-e-alistanas","first","instock","taxable","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gaita de fol de Julio Prada - Pablo Carpintero<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pablocarpintero.es\/es\/producto\/gaita-de-fol-de-julio-prada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gaita de fol de Julio Prada - Pablo Carpintero\" \/>\n<meta property=\"og:description\" content=\"\ufeffJulio Prada (1924-2005) foi gaiteiro en Ungilde (Seabra, Zamora), un dos mitos desta terra e unha referencia para os gaiteiros do noroeste peninsular. Como t\u00f3dolos grandes gaiteiros empregou unha formidable gaita que, \u00e1 s\u00faa morte, cedeu o seu compa\u00f1eiro de alboradas Edelio Gonz\u00e1lez, gran tamboriteiro e cantador onde os haxa. Edelio depositou esta fermosa gaita, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pablocarpintero.es\/es\/producto\/gaita-de-fol-de-julio-prada\/\" \/>\n<meta property=\"og:site_name\" content=\"Pablo Carpintero\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-29T07:35:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pablocarpintero.es\/wp-content\/uploads\/2021\/11\/DSC_5502.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1518\" \/>\n\t<meta property=\"og:image:height\" content=\"1007\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pablocarpintero.es\\\/producto\\\/gaita-de-fol-de-julio-prada\\\/\",\"url\":\"https:\\\/\\\/pablocarpintero.es\\\/producto\\\/gaita-de-fol-de-julio-prada\\\/\",\"name\":\"Gaita de fol de Julio Prada - Pablo Carpintero\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pablocarpintero.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pablocarpintero.es\\\/producto\\\/gaita-de-fol-de-julio-prada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pablocarpintero.es\\\/producto\\\/gaita-de-fol-de-julio-prada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pablocarpintero.es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/DSC_5502.jpg\",\"datePublished\":\"2021-11-08T07:37:28+00:00\",\"dateModified\":\"2025-03-29T07:35:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pablocarpintero.es\\\/producto\\\/gaita-de-fol-de-julio-prada\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pablocarpintero.es\\\/producto\\\/gaita-de-fol-de-julio-prada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pablocarpintero.es\\\/producto\\\/gaita-de-fol-de-julio-prada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pablocarpintero.es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/DSC_5502.jpg\",\"contentUrl\":\"https:\\\/\\\/pablocarpintero.es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/DSC_5502.jpg\",\"width\":1518,\"height\":1007},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pablocarpintero.es\\\/producto\\\/gaita-de-fol-de-julio-prada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/pablocarpintero.es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/pablocarpintero.es\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gaita de fol de Julio Prada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pablocarpintero.es\\\/#website\",\"url\":\"https:\\\/\\\/pablocarpintero.es\\\/\",\"name\":\"Pablo Carpintero\",\"description\":\"Otro sitio realizado con WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pablocarpintero.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gaita de fol de Julio Prada - Pablo Carpintero","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pablocarpintero.es\/es\/producto\/gaita-de-fol-de-julio-prada\/","og_locale":"es_ES","og_type":"article","og_title":"Gaita de fol de Julio Prada - Pablo Carpintero","og_description":"\ufeffJulio Prada (1924-2005) foi gaiteiro en Ungilde (Seabra, Zamora), un dos mitos desta terra e unha referencia para os gaiteiros do noroeste peninsular. Como t\u00f3dolos grandes gaiteiros empregou unha formidable gaita que, \u00e1 s\u00faa morte, cedeu o seu compa\u00f1eiro de alboradas Edelio Gonz\u00e1lez, gran tamboriteiro e cantador onde os haxa. Edelio depositou esta fermosa gaita, [&hellip;]","og_url":"https:\/\/pablocarpintero.es\/es\/producto\/gaita-de-fol-de-julio-prada\/","og_site_name":"Pablo Carpintero","article_modified_time":"2025-03-29T07:35:40+00:00","og_image":[{"width":1518,"height":1007,"url":"https:\/\/pablocarpintero.es\/wp-content\/uploads\/2021\/11\/DSC_5502.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pablocarpintero.es\/producto\/gaita-de-fol-de-julio-prada\/","url":"https:\/\/pablocarpintero.es\/producto\/gaita-de-fol-de-julio-prada\/","name":"Gaita de fol de Julio Prada - Pablo Carpintero","isPartOf":{"@id":"https:\/\/pablocarpintero.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pablocarpintero.es\/producto\/gaita-de-fol-de-julio-prada\/#primaryimage"},"image":{"@id":"https:\/\/pablocarpintero.es\/producto\/gaita-de-fol-de-julio-prada\/#primaryimage"},"thumbnailUrl":"https:\/\/pablocarpintero.es\/wp-content\/uploads\/2021\/11\/DSC_5502.jpg","datePublished":"2021-11-08T07:37:28+00:00","dateModified":"2025-03-29T07:35:40+00:00","breadcrumb":{"@id":"https:\/\/pablocarpintero.es\/producto\/gaita-de-fol-de-julio-prada\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pablocarpintero.es\/producto\/gaita-de-fol-de-julio-prada\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pablocarpintero.es\/producto\/gaita-de-fol-de-julio-prada\/#primaryimage","url":"https:\/\/pablocarpintero.es\/wp-content\/uploads\/2021\/11\/DSC_5502.jpg","contentUrl":"https:\/\/pablocarpintero.es\/wp-content\/uploads\/2021\/11\/DSC_5502.jpg","width":1518,"height":1007},{"@type":"BreadcrumbList","@id":"https:\/\/pablocarpintero.es\/producto\/gaita-de-fol-de-julio-prada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pablocarpintero.es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/pablocarpintero.es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Gaita de fol de Julio Prada"}]},{"@type":"WebSite","@id":"https:\/\/pablocarpintero.es\/#website","url":"https:\/\/pablocarpintero.es\/","name":"Pablo Carpintero","description":"Otro sitio realizado con WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pablocarpintero.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/pablocarpintero.es\/es\/wp-json\/wp\/v2\/product\/813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pablocarpintero.es\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pablocarpintero.es\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/pablocarpintero.es\/es\/wp-json\/wp\/v2\/comments?post=813"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pablocarpintero.es\/es\/wp-json\/wp\/v2\/media\/2613"}],"wp:attachment":[{"href":"https:\/\/pablocarpintero.es\/es\/wp-json\/wp\/v2\/media?parent=813"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/pablocarpintero.es\/es\/wp-json\/wp\/v2\/product_brand?post=813"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pablocarpintero.es\/es\/wp-json\/wp\/v2\/product_cat?post=813"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pablocarpintero.es\/es\/wp-json\/wp\/v2\/product_tag?post=813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}